{"id":8928,"date":"2023-04-21T09:37:20","date_gmt":"2023-04-21T07:37:20","guid":{"rendered":"https:\/\/hajoona.com\/experiencia\/"},"modified":"2026-07-13T15:12:56","modified_gmt":"2026-07-13T13:12:56","slug":"experiencia","status":"publish","type":"page","link":"https:\/\/hajoona.com\/es\/experiencia\/","title":{"rendered":"Experiencia"},"content":{"rendered":"\r\n\r\n\r\n\r\n<div id=\"block-b66dc19606ddb1821d41fb0b0bd7755e6a978d9cda6ee\" \r\n    class=\"wp-block-acf-hero-slider alignfull acf-block-component\"\r\n    style=\"margin-top:0;margin-bottom:0;\">\r\n\r\n<div class=\"hero-slider-block__media\">\r\n\r\n    <img decoding=\"async\" class=\"slide-1 active\"\r\n        src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2023\/03\/GettyImages-1305346790.jpg\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2023\/03\/GettyImages-1305346790-414x276.jpg 414w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/03\/GettyImages-1305346790-768x512.jpg 768w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/03\/GettyImages-1305346790-1024x683.jpg 1024w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/03\/GettyImages-1305346790-1536x1024.jpg 1536w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/03\/GettyImages-1305346790.jpg 1920w\"\r\n        alt=\"Nature is our Super\u00adpower.\">\r\n<\/div>\r\n<div class=\"hero-slider-block__content has-product-apricot-background-color\">\r\n\r\n    <div class=\"hero-slider-block__bg\"><\/div>\r\n\r\n    <div\r\n        class=\"hero-slider-block__content-inner has-global-padding is-layout-constrained wp-block-group is-style-5-cols\">\r\n\r\n        <div class=\"content-inner__slide-container\">\r\n\r\n                        <span data-bg-color=\"product-apricot\"\r\n                class=\"content-inner__slide is-layout-constrained slide-1 active has-product-apricot-background-color  active\">\r\n\r\n                                <h2 class=\"slide__head\">La naturaleza es nuestro superpower.<\/h2>\r\n                \r\n                                <h4 class=\"slide__subhead\">Las m\u00e1s altas exigencias, ingredientes naturales de primera calidad, resultados \u00fanicos.<\/h4>\r\n                \r\n                \r\n            <\/span>\r\n\r\n\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n    <div class=\"hero-slider-block__index has-copy-s-font-size\">\r\n        <ul>\r\n            \r\n            <!-- <li><a><span class=\"index\">1<\/span><span class=\"line\"><\/span><\/a><\/li>\r\n            <li class=\"active\"><a><span class=\"index\">1<\/span><span class=\"line\"><\/span><\/a><\/li>\r\n            <li><a><span class=\"index\">1<\/span><span class=\"line\"><\/span><\/a><\/li> -->\r\n        <\/ul>\r\n    <\/div>\r\n\r\n<\/div>\r\n\r\n\r\n<span id=\"trigger-block-b66dc19606ddb1821d41fb0b0bd7755e6a978d9cda6ee\"><\/span>\r\n<script>\r\nif (typeof initHeroSliderBlock !== 'undefined') {\r\n    initHeroSliderBlock(document.querySelector(`#trigger-block-b66dc19606ddb1821d41fb0b0bd7755e6a978d9cda6ee`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initHeroSliderBlock(document.querySelector(`#trigger-block-b66dc19606ddb1821d41fb0b0bd7755e6a978d9cda6ee`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<\/div>\n\n\n<div class=\"wp-block-group alignfull has-prime-white-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0\">\n<div class=\"wp-block-columns alignwide align-items-baseline is-layout-flex wp-container-core-columns-is-layout-07b35940 wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--4);margin-bottom:var(--wp--preset--spacing--4)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(27.42px, 1.714rem + ((1vw - 3.2px) * 1.748), 47px);\">Verdaderos tesoros: Las sustancias vegetales secundarias<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Verdaderos h\u00e9roes de la naturaleza<\/strong><br>Utilizamos el superpoder de las sustancias vegetales secundarias. Ayudan a las plantas a adaptarse a su entorno. Ahuyentan a los depredadores, protegen del sol, la lluvia o los hongos, act\u00faan como reguladores del crecimiento y tambi\u00e9n sirven como aromatizantes, fragancias o colorantes.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los humanos tambi\u00e9n podemos beneficiarnos de este superpoder manteniendo una dieta equilibrada. La fruta, la verdura, los frutos secos, las setas y las hierbas contienen diversos ingredientes valiosos, como vitaminas, minerales y sustancias vegetales secundarias. Estas sustancias cumplen distintas funciones en las plantas, y tambi\u00e9n pueden contribuir a la salud y el bienestar de los humanos como parte de una dieta equilibrada.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un ejemplo: el resveratrol es una sustancia vegetal secundaria que se encuentra en las uvas rojas, las frambuesas y los granos de cacao. Cumple funciones protectoras en la planta, por ejemplo contra las influencias medioambientales. En la dieta, el resveratrol es un componente de los alimentos ricos en polifenoles y contribuye al bienestar general.  <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-4-cols-content is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La industria farmac\u00e9utica no da prioridad al poder de las plantas, ya que las empresas creen que no se pueden obtener beneficios significativos de los ingredientes de las plantas. Por ello, a menudo no est\u00e1n dispuestas a financiar estudios sobre fitoqu\u00edmicos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por tanto, nuestro principal objetivo es: seguir investigando sobre los fitoqu\u00edmicos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los \u00faltimos descubrimientos de la ciencia nutricional y de la salud sobre el potencial beneficioso para la salud de las sustancias vegetales se incorporan regularmente al desarrollo de productos de hajoona. De este modo, las recetas existentes pueden optimizarse y las nuevas crearse e implementarse junto con nuestros proveedores. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text alignfull has-media-on-the-right is-stacked-on-mobile is-image-fill-element is-style-square has-prime-white-color has-prime-off-white-background-color has-text-color has-background\" style=\"margin-top:0;margin-bottom:0\" id=\"longevity\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-group is-style-5-cols has-prime-black-color has-text-color has-link-color wp-elements-1 has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--4);margin-bottom:var(--wp--preset--spacing--4)\">\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(33.419px, 2.089rem + ((1vw - 3.2px) * 2.373), 60px);\">La longevidad, simplificada.<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:clamp(18.959px, 1.185rem + ((1vw - 3.2px) * 0.986), 30px);\">Health. Freedom. Growth. En tu vida cotidiana.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La longevidad no s\u00f3lo significa vivir m\u00e1s, sino vivir <strong>mejor<\/strong>: con energ\u00eda, salud y verdadera calidad de vida. Aqu\u00ed es exactamente donde entra hajoona: <strong>altamente compleja en investigaci\u00f3n y formulaci\u00f3n, f\u00e1cil de usar, perceptible en la vida cotidiana.<\/strong> Nuestros productos, programas y nuestra comunidad te ayudan a establecer rutinas que duran. <\/p>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"2120\" height=\"1414\" src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/10\/Longevity-made-simple.-hajoona.jpg\" alt=\"Esta foto muestra a tres alegres mujeres en un c\u00e1lido abrazo: un poderoso s\u00edmbolo de comunidad intergeneracional, empoderamiento y la energ\u00eda positiva de la comunidad hajoona.\" class=\"wp-image-6974 size-full\" style=\"object-position:48% 50%\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/10\/Longevity-made-simple.-hajoona.jpg 2120w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/10\/Longevity-made-simple.-hajoona-768x512.jpg 768w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/10\/Longevity-made-simple.-hajoona-1024x683.jpg 1024w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/10\/Longevity-made-simple.-hajoona-414x276.jpg 414w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/10\/Longevity-made-simple.-hajoona-1536x1024.jpg 1536w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/10\/Longevity-made-simple.-hajoona-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 2120px) 100vw, 2120px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-prime-white-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0\">\n<div class=\"wp-block-columns alignwide align-items-baseline is-layout-flex wp-container-core-columns-is-layout-07b35940 wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--4);margin-bottom:var(--wp--preset--spacing--4)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">La Longevity, simplificada.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Longevidad sencilla y eficaz.<\/strong>  Adoptamos un enfoque hol\u00edstico de la longevidad y traducimos esta afirmaci\u00f3n en soluciones espec\u00edficas adecuadas para el uso diario. Nuestros productos favorecen el aporte diario de nutrientes esenciales y ayudan a mantener el equilibrio y la vitalidad. Pero la Longevidad es mucho m\u00e1s: es un concepto de vida que une cuerpo, mente y estilo de vida. Reunimos a personas que sit\u00faan la salud, la comunidad y la autodeterminaci\u00f3n en el centro, y creamos as\u00ed un entorno en el que se crea <strong>una verdadera calidad de vida a largo plazo <\/strong>. <strong>Los cuatro pilares de la longevidad en hajoona<\/strong>    <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Salud <\/strong>&#8211; Ayudamos a las personas a reforzar su base f\u00edsica y a adoptar medidas preventivas para garantizar su bienestar. Porque la verdadera longevidad comienza con la decisi\u00f3n diaria de llevar un estilo de vida saludable.   <\/li>\n\n\n\n<li><strong>Felicidad y realizaci\u00f3n<\/strong> &#8211; Una vida larga es valiosa cuando es autodeterminada y significativa. Animamos a las personas a vivir valores, alcanzar objetivos y cultivar activamente la comunidad.   <\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-4-cols-content is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li><strong>Crecimiento personal <\/strong>&#8211; La longevidad tambi\u00e9n significa madurar mental y emocionalmente: aprender, probar cosas nuevas, desarrollar tu propia personalidad.  <\/li>\n\n\n\n<li><strong>Libertad financiera<\/strong> &#8211; Quienes son financieramente independientes tienen la libertad de moldear su vida como deseen. hajoona ofrece un s\u00f3lido modelo de negocio que permite a las personas construir una base estable para su futuro. <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El resultado es una combinaci\u00f3n \u00fanica de salud, desarrollo personal y autodeterminaci\u00f3n financiera.<\/strong>  Esta es la esencia de la Longevidad en hajoona: hacer posible que las personas no s\u00f3lo vivan m\u00e1s, sino que vivan mejor, m\u00e1s felices y m\u00e1s libres.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\r\n\r\n\r\n\r\n<div id=\"block-52deeb45dde2e149cbfe840d78a0c4316a978d9ce1d30\" \r\n    class=\"wp-block-acf-teaser alignfull has-product-green-background-color has-background has-prime-white-color has-text-color acf-block-component\"\r\n    style=\"margin-top:0;margin-bottom:0;\">\r\n\r\n\r\n<div class=\"highlight__offset-text highlight__offset-text--top alignright\"><span\r\n        class=\"text\">mejor<\/div>\r\n\r\n<div class=\"highlight__inner-block\">\r\n\r\n    <div class=\"highlight__copy\"><span>Apostamos por el poder de la naturaleza y realizamos labores de sensibilizaci\u00f3n sobre la alimentaci\u00f3n saludable para mejorar cada d\u00eda el bienestar de todas las personas.<\/span>\r\n\r\n        \r\n    <\/div>\r\n        <div class=\"highlight__image\">\r\n        <img decoding=\"async\" src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/Nature.jpg\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/Nature-414x414.jpg 414w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/Nature-768x768.jpg 768w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/Nature-1024x1024.jpg 1024w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/Nature-1536x1536.jpg 1536w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/Nature-2048x2048.jpg 2048w\"\r\n            alt=\"Best quality\">\r\n    <\/div>\r\n\r\n<\/div>\r\n\r\n<div class=\"highlight__offset-text highlight__offset-text--bottom alignleft\"><span\r\n        class=\"text\">calidad<\/div>\r\n\r\n\r\n\r\n<span id=\"trigger-block-52deeb45dde2e149cbfe840d78a0c4316a978d9ce1d30\"><\/span>\r\n<script>\r\nif (typeof initTileMenuBlock !== 'undefined') {\r\n    initTileMenuBlock(document.querySelector(`#trigger-block-52deeb45dde2e149cbfe840d78a0c4316a978d9ce1d30`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initTileMenuBlock(document.querySelector(`#trigger-block-52deeb45dde2e149cbfe840d78a0c4316a978d9ce1d30`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<\/div>\n\n\n<div class=\"wp-block-columns alignwide align-items-baseline is-layout-flex wp-container-core-columns-is-layout-07b35940 wp-block-columns-is-layout-flex\" id=\"informativo\" style=\"margin-top:var(--wp--preset--spacing--4);margin-bottom:var(--wp--preset--spacing--4)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 id=\"Beirat\" class=\"wp-block-heading\" style=\"font-size:clamp(27.42px, 1.714rem + ((1vw - 3.2px) * 1.748), 47px);\">Consejo Cient\u00edfico Asesor<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-4-cols-content is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">hajoona est\u00e1 comprometida con el desarrollo y la optimizaci\u00f3n continuos de productos, procesos y sistemas. Por ello, hemos decidido crear un consejo asesor cient\u00edfico. Nos sentimos orgullosos y honrados de que personalidades de renombre de los campos de la investigaci\u00f3n y la docencia, as\u00ed como de la empresa, hayan aceptado apoyar activamente a hajoona en calidad de asesores.  <\/p>\n<\/div>\n<\/div>\n\n\n\r\n<style>\r\ndiv#block-9e256477236a6868f7a5435f28f36ac16a978d9ce3821 .slide {\r\n    width: 36rem !important;\r\n}\r\n\r\ndiv#block-9e256477236a6868f7a5435f28f36ac16a978d9ce3821 .slide__image-container {\r\n    aspect-ratio: 1\/1.25;\r\n    font-size: 8rem;\r\n}\r\n\r\ndiv#block-9e256477236a6868f7a5435f28f36ac16a978d9ce3821 .slide__image-container img {\r\n    object-fit: contain;\r\n    object-position: left bottom;\r\n}\r\n<\/style>\r\n\r\n\r\n\r\n<div id=\"block-9e256477236a6868f7a5435f28f36ac16a978d9ce3821\" \r\n    class=\"wp-block-acf-carousel has-prime-black-color has-text-color acf-block-component\"\r\n    style=\"margin-bottom:var(--wp--preset--spacing--5);\">\r\n<div class=\"carousel-container has-global-padding is-layout-constrained\"\r\n    style=\"\">\r\n    <button class=\"carousel-control carousel-control--prev no-button-styling prev-cursor\"><\/button>\r\n    <button class=\"carousel-control carousel-control--next no-button-styling next-cursor\"><\/button>\r\n\r\n    <div class=\"carousel-pos  alignwide\">\r\n        <div class=\"carousel\" data-slick='{\"mobileFirst\":true,\"variableWidth\":false,\"infinite\":false,\"slidesToShow\":1,\"slidesToScroll\":1}'>\r\n\r\n            \r\n            <a class=\"slide\" href=\"javascript:void(0);\">\r\n            <div class=\"slide__image-container\">\r\n                <img decoding=\"async\" class=\"slide-1 active\"\r\n                    src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Beghini-Alessandro-10.2024-EUC-I-e1741776079415.jpg\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Beghini-Alessandro-10.2024-EUC-I-e1741776079415.jpg 1023w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Beghini-Alessandro-10.2024-EUC-I-e1741776079415-716x768.jpg 716w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Beghini-Alessandro-10.2024-EUC-I-e1741776079415-954x1024.jpg 954w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Beghini-Alessandro-10.2024-EUC-I-e1741776079415-386x414.jpg 386w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Beghini-Alessandro-10.2024-EUC-I-e1741776079415-768x824.jpg 768w\"\r\n                    alt=\"Prof. Alessandro Beghini geht l\u00e4chelnd einen hellen Flur entlang. Er tr\u00e4gt einen dunkelblauen Anzug mit einem hellblauen Hemd, ohne Krawatte. Seine rechte Hand steckt in der Hosentasche, w\u00e4hrend er entspannt in die Kamera blickt. Der Hintergrund zeigt eine moderne Architektur mit viel Licht und Glas.\">\r\n\r\n                \r\n                \r\n            <\/div>\r\n\r\n                        <h3 class=\"slide__head\">Prof. Alessandro Beghini<\/h3>\r\n            \r\n                        <h4 class=\"slide__subhead\">Catedr\u00e1tico de Biolog\u00eda Molecular en el Departamento de Ciencias de la Salud (DISS) de la Facultad de Medicina de la Universidad de Mil\u00e1n y redactor jefe del Atlas de Gen\u00e9tica y Citogen\u00e9tica en Oncolog\u00eda y Hematolog\u00eda. Sus l\u00edneas de investigaci\u00f3n se centran en la biolog\u00eda molecular del c\u00e1ncer y abarcan la interferencia molecular en las v\u00edas metab\u00f3licas que provocan el c\u00e1ncer.<\/h4>\r\n            \r\n            <\/a>\r\n            <a class=\"slide\" href=\"javascript:void(0);\">\r\n            <div class=\"slide__image-container\">\r\n                <img decoding=\"async\" class=\"slide-2\"\r\n                    src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Rolf-Schmiel-e1741776555840.png\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Rolf-Schmiel-e1741776555840.png 916w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Rolf-Schmiel-e1741776555840-680x768.png 680w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Rolf-Schmiel-e1741776555840-906x1024.png 906w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Rolf-Schmiel-e1741776555840-366x414.png 366w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Rolf-Schmiel-e1741776555840-768x868.png 768w\"\r\n                    alt=\"Dipl.-Psychologe Rolf Schmiel steht l\u00e4chelnd in einem modernen Geb\u00e4ude. Er tr\u00e4gt eine braune Stoffjacke, ein hellblaues Hemd und eine Brille. Seine linke Hand steckt l\u00e4ssig in der Hosentasche, w\u00e4hrend seine rechte Hand locker an der Seite h\u00e4ngt. Im Hintergrund ist eine helle, verschwommene Architektur mit gro\u00dfen Fenstern und modernen Strukturelementen zu sehen.\">\r\n\r\n                \r\n                \r\n            <\/div>\r\n\r\n                        <h3 class=\"slide__head\">Psic\u00f3logo titulado Rolf Schmiel<\/h3>\r\n            \r\n                        <h4 class=\"slide__subhead\">Es uno de los psic\u00f3logos m\u00e1s conocidos de Alemania. Cada semana participa como experto en programas de televisi\u00f3n, radio y podcasts. Tanto las grandes empresas internacionales como las pymes de larga tradici\u00f3n lo valoran como un ponente principal carism\u00e1tico.<\/h4>\r\n            \r\n            <\/a>\r\n            <a class=\"slide\" href=\"javascript:void(0);\">\r\n            <div class=\"slide__image-container\">\r\n                <img decoding=\"async\" class=\"slide-3\"\r\n                    src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/An-Zhigang-scaled.jpg\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/An-Zhigang-414x276.jpg 414w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/An-Zhigang-768x512.jpg 768w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/An-Zhigang-1024x683.jpg 1024w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/An-Zhigang-1536x1024.jpg 1536w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/An-Zhigang-2048x1365.jpg 2048w\"\r\n                    alt=\"Prof. Dr. Zhigang An sitzt entspannt auf einer Holzbank im Freien. Er tr\u00e4gt ein graues Sakko \u00fcber einem dunkelblauen Pullover und einem hellen Hemd. Er blickt nachdenklich zur Seite. Im Hintergrund sind gr\u00fcne B\u00e4ume mit frischem Laub und weichem Sonnenlicht zu sehen.\">\r\n\r\n                \r\n                \r\n            <\/div>\r\n\r\n                        <h3 class=\"slide__head\">Prof. Dr. Zhigang An<\/h3>\r\n            \r\n                        <h4 class=\"slide__subhead\">Profesor de la Universidad Forestal del Noreste (NEFU, Harbin, Rep\u00fablica Popular China) que investiga, entre otras cosas, los beneficios de los fitoqu\u00edmicos para la salud humana.<\/h4>\r\n            \r\n            <\/a>\r\n            <a class=\"slide\" href=\"javascript:void(0);\">\r\n            <div class=\"slide__image-container\">\r\n                <img decoding=\"async\" class=\"slide-4\"\r\n                    src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Dr.-med.-Dr.-rer.-nat.-Bernhard-Uehleke-10.2024-EUC-e1741776813187.jpg\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Dr.-med.-Dr.-rer.-nat.-Bernhard-Uehleke-10.2024-EUC-e1741776813187.jpg 850w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Dr.-med.-Dr.-rer.-nat.-Bernhard-Uehleke-10.2024-EUC-e1741776813187-673x768.jpg 673w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Dr.-med.-Dr.-rer.-nat.-Bernhard-Uehleke-10.2024-EUC-e1741776813187-363x414.jpg 363w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Prof.-Dr.-med.-Dr.-rer.-nat.-Bernhard-Uehleke-10.2024-EUC-e1741776813187-768x876.jpg 768w\"\r\n                    alt=\"Prof. Dr. med. Dr. rer. nat. Bernhard Uehleke steht in einem modernen, hellen Geb\u00e4ude mit verschr\u00e4nkten Armen und l\u00e4chelt freundlich in die Kamera. Er tr\u00e4gt einen dunkelgrauen Anzug mit feinen Streifen und ein hellrosanes Hemd. Im Hintergrund sind unscharfe, architektonische Strukturen zu sehen.\">\r\n\r\n                \r\n                \r\n            <\/div>\r\n\r\n                        <h3 class=\"slide__head\">Prof. Dr. med. Dr. rer. nat. Bernhard Uehleke<\/h3>\r\n            \r\n                        <h4 class=\"slide__subhead\">Es uno de los principales expertos en los campos de la medicina natural y la fitoterapia. Inicialmente, llev\u00f3 a cabo con \u00e9xito su labor investigadora en la industria farmac\u00e9utica, antes de dedicarse a la medicina natural e impartir clases e investigar en prestigiosas instituciones acad\u00e9micas, como la Charit\u00e9 de Berl\u00edn, el Hospital Universitario de Z\u00farich y la Escuela Superior de Salud y Deporte de Berl\u00edn. Sus publicaciones y libros especializados gozan de reconocimiento mundial.<\/h4>\r\n            \r\n            <\/a>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n<span id=\"trigger-block-9e256477236a6868f7a5435f28f36ac16a978d9ce3821\"><\/span>\r\n<script>\r\nif (typeof initCarouselBlock !== 'undefined') {\r\n    initCarouselBlock(document.querySelector(`#trigger-block-9e256477236a6868f7a5435f28f36ac16a978d9ce3821`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initCarouselBlock(document.querySelector(`#trigger-block-9e256477236a6868f7a5435f28f36ac16a978d9ce3821`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<\/div>\n\n\n<div class=\"wp-block-media-text alignfull is-stacked-on-mobile is-image-fill-element is-style-square has-prime-white-color has-product-blue-background-color has-text-color has-background\" style=\"margin-top:0;margin-bottom:0\" id=\"calidad\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/20220405_hajoona-08-1-Ueberflug-heiko-test-1024x1024.jpg\" alt=\"Texto alternativo (accesible y descriptivo)\nLas cajas de varios productos de colores de la marca hajoona est\u00e1n una al lado de la otra. Los envases en verde, morado, blanco, gris y azul llevan las inscripciones &quot;Balance&quot;, &quot;Vitality&quot;, &quot;Glow&quot;, &quot;Reset&quot; y &quot;Performance&quot;. Las cajas tienen un dise\u00f1o moderno, con tipograf\u00eda clara y c\u00f3digo de colores.  \n\" class=\"wp-image-2446 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/20220405_hajoona-08-1-Ueberflug-heiko-test-1024x1024.jpg 1024w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/20220405_hajoona-08-1-Ueberflug-heiko-test-768x768.jpg 768w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/20220405_hajoona-08-1-Ueberflug-heiko-test-414x414.jpg 414w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/20220405_hajoona-08-1-Ueberflug-heiko-test-1536x1536.jpg 1536w, https:\/\/hajoona.com\/wp-content\/uploads\/2023\/04\/20220405_hajoona-08-1-Ueberflug-heiko-test-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-group is-style-5-cols has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--4);margin-bottom:var(--wp--preset--spacing--4)\">\n<h2 class=\"wp-block-heading has-prime-white-color has-text-color\" style=\"font-size:clamp(27.42px, 1.714rem + ((1vw - 3.2px) * 1.748), 47px);\">Excelencia probada.<br>La mejor calidad, los mejores productos.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La m\u00e1xima calidad es nuestra principal prioridad. Por eso sometemos voluntariamente la calidad y composici\u00f3n de nuestros productos a controles peri\u00f3dicos por parte de institutos independientes. <\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide align-items-baseline is-layout-flex wp-container-core-columns-is-layout-fcd98b5c wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--3);margin-bottom:var(--wp--preset--spacing--3)\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Somos muy exigentes con nosotros mismos y con nuestros productos. Por eso trabajamos con una selecci\u00f3n de socios de renombre que ponen constantemente a prueba nuestro trabajo y garantizan que cumplamos nuestras propias <strong>exigencias<\/strong>. Nuestro <strong>consejo cient\u00edfico<\/strong> de investigadores de las universidades de Heidelberg y Mil\u00e1n, que nos asesoran sobre el desarrollo y la composici\u00f3n de nuestras f\u00f3rmulas, tiene una importancia capital. <br>Nuestros productos se someten <strong>a estrictos controles de calidad<\/strong> antes de ser dosificados con precisi\u00f3n y embotellados en rigurosas condiciones higi\u00e9nicas. Adem\u00e1s de nuestros propios controles -en curso-, nuestros productos tambi\u00e9n son supervisados a intervalos regulares por el <strong>laboratorio de pruebas independiente Institut Kurz <\/strong>, y la calidad del producto con respecto a los ingredientes que contiene se comprueba y garantiza continuamente, lo que se documenta con la concesi\u00f3n del <strong>sello Kurz<\/strong>. Tambi\u00e9n participamos en la principal asociaci\u00f3n del sector de complementos alimenticios, NEM e.V., para promover normas estrictas en el desarrollo y comercializaci\u00f3n de complementos alimenticios en todo el mercado.    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Especialmente relevante para los <strong>deportistas<\/strong>: Nuestros productos figuran en la <strong>Lista de Colonia\u00ae <\/strong>. La inclusi\u00f3n en esta lista se basa en un an\u00e1lisis realizado por un laboratorio independiente, en el que se analizan los productos en busca de sustancias seleccionadas relevantes para el dopaje. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-default is-layout-flex wp-container-core-group-is-layout-18adc3a5 wp-block-group-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--4);margin-bottom:var(--wp--preset--spacing--4);padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-ebdb8cf3 wp-block-group-is-layout-constrained\" style=\"padding-top:0;padding-right:var(--wp--preset--spacing--3);padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-f6373ea1 wp-block-group-is-layout-flex\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<figure class=\"wp-block-image size-large is-resized\" style=\"margin-top:var(--wp--preset--spacing--2);margin-right:var(--wp--preset--spacing--2);margin-bottom:var(--wp--preset--spacing--2);margin-left:var(--wp--preset--spacing--2)\"><a href=\"https:\/\/bvi50plus.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"274\" src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Logo-Bundesverband-Initiative-50Plus-Verbraucherempfehlung_black-1024x274.png\" alt=\"Logotipo - Bundesverband Initiative 50Plus - Recomendaci\u00f3n del consumidor\" class=\"wp-image-5361\" style=\"width:348px;height:auto\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Logo-Bundesverband-Initiative-50Plus-Verbraucherempfehlung_black-1024x274.png 1024w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Logo-Bundesverband-Initiative-50Plus-Verbraucherempfehlung_black-768x206.png 768w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Logo-Bundesverband-Initiative-50Plus-Verbraucherempfehlung_black-414x111.png 414w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Logo-Bundesverband-Initiative-50Plus-Verbraucherempfehlung_black-1536x411.png 1536w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Logo-Bundesverband-Initiative-50Plus-Verbraucherempfehlung_black-2048x548.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\" style=\"margin-top:var(--wp--preset--spacing--2);margin-right:var(--wp--preset--spacing--2);margin-bottom:var(--wp--preset--spacing--2);margin-left:var(--wp--preset--spacing--2)\"><a href=\"https:\/\/www.cos.uni-heidelberg.de\/de\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"704\" height=\"241\" src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/LOGO_COS_Black.png\" alt=\"\" class=\"wp-image-5365\" style=\"width:330px;height:auto\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/LOGO_COS_Black.png 704w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/LOGO_COS_Black-414x142.png 414w\" sizes=\"auto, (max-width: 704px) 100vw, 704px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-ebdb8cf3 wp-block-group-is-layout-constrained\" style=\"padding-top:0;padding-right:var(--wp--preset--spacing--3);padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-f6373ea1 wp-block-group-is-layout-flex\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<figure class=\"wp-block-image size-full is-resized\" style=\"margin-top:0;margin-right:var(--wp--preset--spacing--2);margin-bottom:0;margin-left:var(--wp--preset--spacing--2)\"><a href=\"https:\/\/www.koelnerliste.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Produkt-der-Koelner-Liste.png\" alt=\"Logotipo de la Lista de Colonia en negro.\" class=\"wp-image-5386\" style=\"width:200px\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Produkt-der-Koelner-Liste.png 1080w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Produkt-der-Koelner-Liste-768x768.png 768w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Produkt-der-Koelner-Liste-1024x1024.png 1024w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Produkt-der-Koelner-Liste-414x414.png 414w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\" style=\"margin-top:0;margin-right:var(--wp--preset--spacing--2);margin-bottom:0;margin-left:var(--wp--preset--spacing--2)\"><a href=\"https:\/\/nem-ev.de\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/NEM-e.V.png\" alt=\"Sello NEM e.V.\" class=\"wp-image-5391\" style=\"width:200px\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/NEM-e.V.png 1080w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/NEM-e.V-768x768.png 768w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/NEM-e.V-1024x1024.png 1024w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/NEM-e.V-414x414.png 414w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\" style=\"margin-top:0;margin-right:var(--wp--preset--spacing--2);margin-bottom:0;margin-left:var(--wp--preset--spacing--2)\"><a href=\"https:\/\/www.institut-kurz.com\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Institut-Prof.-Dr.-Georg-Kurz-GmbH.png\" alt=\"Sello del Instituto Kurz  \" class=\"wp-image-5395\" style=\"width:200px\" srcset=\"https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Institut-Prof.-Dr.-Georg-Kurz-GmbH.png 1080w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Institut-Prof.-Dr.-Georg-Kurz-GmbH-768x768.png 768w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Institut-Prof.-Dr.-Georg-Kurz-GmbH-1024x1024.png 1024w, https:\/\/hajoona.com\/wp-content\/uploads\/2025\/03\/Institut-Prof.-Dr.-Georg-Kurz-GmbH-414x414.png 414w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-prime-white-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" id=\"FAQ\" style=\"margin-top:0;margin-bottom:0;padding-bottom:var(--wp--preset--spacing--5)\">\n<div class=\"wp-block-columns alignwide align-items-baseline is-layout-flex wp-container-core-columns-is-layout-9073d158 wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--5);margin-bottom:var(--wp--preset--spacing--5)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading is-style-5-cols\" style=\"font-size:clamp(27.42px, 1.714rem + ((1vw - 3.2px) * 1.748), 47px);\">Tus preguntas frecuentes <br>de un vistazo.<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-4-cols-content is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 es el concepto de producto hajoona y qu\u00e9 son las sustancias vitales? Respondemos a \u00e9stas y a muchas otras preguntas en nuestra secci\u00f3n de Preguntas frecuentes. <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide align-items-baseline is-layout-flex wp-container-core-columns-is-layout-9073d158 wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--5);margin-bottom:var(--wp--preset--spacing--5)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:var(--wp--preset--spacing--2);font-size:clamp(20px, 1.25rem + ((1vw - 3.2px) * 1.071), 32px);\">Informaci\u00f3n sobre nuestros productos<\/h3>\n\n\n\r\n\r\n\r\n<div id=\"block-f1d9f7333003d5349e58c3fa733dad6e6a978d9ceac9d\" \r\n    class=\"wp-block-acf-accordion align acf-block-component\"\r\n    style=\"\">\r\n\r\n\r\n<h5 class=\"accordion__title\">\r\n    <button class=\"no-button-styling\">Concepto de producto hajoona<\/button>\r\n<\/h5>\r\n\r\n\r\n<div class=\"accordion__content\">\r\n    <div class=\"acf-innerblocks-container\">\n\n<ul class=\"wp-block-list is-style-no-marker\">\n<li><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy en d\u00eda, cada vez es m\u00e1s dif\u00edcil comer bien. La gente se desplaza y est\u00e1 en constante movimiento, tiene grandes exigencias en el trabajo y quiere optimizarse cada vez m\u00e1s. <br><br>Hay cuatro grandes retos que ponen a prueba la salud:  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Falta de ejercicio \/ sobrepeso<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Acidosis<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estr\u00e9s<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Contenido en nutrientes de nuestros alimentos<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Las pruebas cient\u00edficas demuestran d\u00f3nde est\u00e1n nuestros retos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El 40% de los hombres y el 45% de las mujeres no hacen suficiente ejercicio.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El 50 % de todos los alemanes tienen sobrepeso (IMC &gt; 25) &#8211; el 25 % son incluso obesos (IMC &gt; 30). Las consecuencias: Enfermedades de la civilizaci\u00f3n (infarto de miocardio, c\u00e1ncer, asma, reumatismo, dolencias articulares y vertebrales). <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se considera que el 80 % de los alemanes est\u00e1n sobreacidificados. Consecuencias: menor rendimiento, cansancio, dolores de cabeza, dolores musculares y articulares, propensi\u00f3n a las infecciones. <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El 60 % de los alemanes sufre estr\u00e9s. El 20 % se siente permanentemente estresado. Las consecuencias: Se reduce la absorci\u00f3n de nutrientes por los intestinos, aumenta la susceptibilidad a las infecciones  <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El contenido en nutrientes ha disminuido un 50 % en 60 a\u00f1os debido a la agricultura intensiva y los monocultivos. Con una dieta convencional, cada vez es m\u00e1s dif\u00edcil satisfacer nuestras necesidades nutricionales. <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Has elegido productos hajoona y eso es bueno. Te ayudar\u00e1n a reponer tus reservas de sustancias vitales y a mantener tu cuerpo y tu mente en equilibrio. Para una mejor salud y m\u00e1s alegr\u00eda de vivir! Los productos hajoona son veganos y est\u00e1n elaborados con ingredientes ecol\u00f3gicos siempre que es posible, y se producen sin aditivos ni edulcorantes. No contienen gluten ni lactosa, est\u00e1n libres de ingenier\u00eda gen\u00e9tica y pesticidas, y se someten a pruebas minuciosas para detectar sustancias nocivas, a fin de garantizar que recibas la mejor calidad de producto.     <\/p>\n\n<\/div><\/div>\r\n\r\n\r\n\r\n<span id=\"trigger-block-f1d9f7333003d5349e58c3fa733dad6e6a978d9ceac9d\"><\/span>\r\n<script>\r\nif (typeof initAccordionBlock !== 'undefined') {\r\n    initAccordionBlock(document.querySelector(`#trigger-block-f1d9f7333003d5349e58c3fa733dad6e6a978d9ceac9d`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initAccordionBlock(document.querySelector(`#trigger-block-f1d9f7333003d5349e58c3fa733dad6e6a978d9ceac9d`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<!-- <img decoding=\"async\" src=\"https:\/\/hajoona.local\/wp-content\/uploads\/2023\/01\/women.jpg\" onload=\"(function(console.log('hi')))(this)\" \/> -->\r\n\r\n<\/div>\n\n\r\n\r\n\r\n<div id=\"block-27cbb0453d5e6a96367ce6120076a14a6a978d9ceb612\" \r\n    class=\"wp-block-acf-accordion align acf-block-component\"\r\n    style=\"\">\r\n\r\n\r\n<h5 class=\"accordion__title\">\r\n    <button class=\"no-button-styling\">Reset 1+2: Immune Health, Microbiome Support, Inner Strength<\/button>\r\n<\/h5>\r\n\r\n\r\n<div class=\"accordion__content\">\r\n    <div class=\"acf-innerblocks-container\">\n\n<ul class=\"wp-block-list is-style-no-marker\">\n<li>El intestino es uno de los \u00f3rganos m\u00e1s importantes de tu cuerpo. Aqu\u00ed es donde se absorben todos los nutrientes, se producen y regulan tus hormonas y se fortalece y mantiene en buena forma tu sistema inmunitario. Por desgracia, el intestino grueso y el delgado son especialmente susceptibles a los efectos perjudiciales de la vida moderna:  <br><br>Los aditivos qu\u00edmicos de los alimentos, los medicamentos, el estr\u00e9s y otros tipos de contaminaci\u00f3n ambiental pueden alterar gravemente su funcionamiento, desequilibrando todo el organismo. Por tanto, una limpieza intestinal regular y eficaz es esencial para tu bienestar a largo plazo. <br><br>hajoona Reset va un paso m\u00e1s all\u00e1 con su principio bif\u00e1sico:<br><br><strong>Reset 1 <\/strong>limpia el intestino con c\u00e1scaras de psilio y lo enriquece con la fibra Nutriose. Esto lo fortalece y crea una flora intestinal sana.<br>Otros ingredientes antiinflamatorios restablecen el equilibrio natural del organismo y regeneran las c\u00e9lulas da\u00f1adas. <br><br>A continuaci\u00f3n, <strong>Reset 2<\/strong> refuerza la flora intestinal con la ayuda de 32 cepas bacterianas altamente dosificadas y activas, y apoya as\u00ed las defensas inmunitarias del organismo y un metabolismo sano de las grasas. Esto sienta las bases para una mejora general del bienestar mental. <\/li>\n<\/ul>\n\n<\/div><\/div>\r\n\r\n\r\n\r\n<span id=\"trigger-block-27cbb0453d5e6a96367ce6120076a14a6a978d9ceb612\"><\/span>\r\n<script>\r\nif (typeof initAccordionBlock !== 'undefined') {\r\n    initAccordionBlock(document.querySelector(`#trigger-block-27cbb0453d5e6a96367ce6120076a14a6a978d9ceb612`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initAccordionBlock(document.querySelector(`#trigger-block-27cbb0453d5e6a96367ce6120076a14a6a978d9ceb612`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<!-- <img decoding=\"async\" src=\"https:\/\/hajoona.local\/wp-content\/uploads\/2023\/01\/women.jpg\" onload=\"(function(console.log('hi')))(this)\" \/> -->\r\n\r\n<\/div>\n\n\r\n\r\n\r\n<div id=\"block-2cff5452a67f1e8d057e8dd8cebadbe96a978d9cebbde\" \r\n    class=\"wp-block-acf-accordion align acf-block-component\"\r\n    style=\"\">\r\n\r\n\r\n<h5 class=\"accordion__title\">\r\n    <button class=\"no-button-styling\">Balance: Weight Loss, Focus &#038; Inner Balance<\/button>\r\n<\/h5>\r\n\r\n\r\n<div class=\"accordion__content\">\r\n    <div class=\"acf-innerblocks-container\">\n\n<ul class=\"wp-block-list is-style-no-marker\">\n<li>Un cuerpo sano y vital tambi\u00e9n requiere una mente clara y centrada. S\u00f3lo esta combinaci\u00f3n te permite desarrollar todo tu potencial cada d\u00eda y alcanzar todos los objetivos que te hayas propuesto. Con hajoona Equilibrio, puedes equilibrar tu cuerpo por la ma\u00f1ana y garantizar la claridad mental. La combinaci\u00f3n \u00fanica de granos de caf\u00e9 verde y tres hongos medicinales tradicionales chinos act\u00faa contra la inflamaci\u00f3n del organismo y reduce as\u00ed tus niveles de estr\u00e9s. El calcio, los amino\u00e1cidos y las prote\u00ednas del arroz y las alubias aseguran el buen funcionamiento de todos los procesos celulares, facilitan el trabajo de tu cuerpo y pueden ayudarte a conseguir tus objetivos de p\u00e9rdida de peso.    <br><br><strong>P\u00c9RDIDA DE PESO<\/strong> Equilibrio ayuda a tu h\u00edgado en el metabolismo (de las grasas) con \u00e1cido clorog\u00e9nico y colina. El calcio, las prote\u00ednas del arroz y las alubias rojas y un completo perfil de amino\u00e1cidos abastecen tus m\u00fasculos y garantizan su mantenimiento y el funcionamiento \u00f3ptimo de todos los procesos celulares. Un h\u00edgado fuerte alivia a los ri\u00f1ones para una desacidificaci\u00f3n eficaz del organismo, de modo que puedan eliminarse los \u00e1cidos que se acumulan en el tejido conjuntivo y adiposo.  <br><br><strong>ENFOQUE Y EQUILIBRIO INTERIOR<\/strong> El caf\u00e9 verde sin tostar, la colina y los hongos medicinales adapt\u00f3genos Ling Zhi, Maitake y Hericium reducen tus niveles de estr\u00e9s y aumentan la claridad y el enfoque. Los amino\u00e1cidos esenciales ayudan a mantener equilibrado tu metabolismo celular. El Hericium tiene un efecto regenerador sobre el sistema nervioso y proporciona concentraci\u00f3n y claridad, mientras que el Reishi, el \u00abrey de las setas medicinales\u00bb, refuerza el sistema inmunitario. En la medicina china, los tres hongos medicinales \u00abmodulan\u00bb el organismo: tanto se equilibra un exceso como un defecto. Nuestros extractos de hongos medicinales se producen cuidadosamente y est\u00e1n presentes en una fuerte proporci\u00f3n de 15:1 en tu hajoona Balance.    <\/li>\n<\/ul>\n\n<\/div><\/div>\r\n\r\n\r\n\r\n<span id=\"trigger-block-2cff5452a67f1e8d057e8dd8cebadbe96a978d9cebbde\"><\/span>\r\n<script>\r\nif (typeof initAccordionBlock !== 'undefined') {\r\n    initAccordionBlock(document.querySelector(`#trigger-block-2cff5452a67f1e8d057e8dd8cebadbe96a978d9cebbde`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initAccordionBlock(document.querySelector(`#trigger-block-2cff5452a67f1e8d057e8dd8cebadbe96a978d9cebbde`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<!-- <img decoding=\"async\" src=\"https:\/\/hajoona.local\/wp-content\/uploads\/2023\/01\/women.jpg\" onload=\"(function(console.log('hi')))(this)\" \/> -->\r\n\r\n<\/div>\n\n\r\n\r\n\r\n<div id=\"block-88e6985c1d772f66b92989d48d7b41246a978d9cec3fc\" \r\n    class=\"wp-block-acf-accordion align acf-block-component\"\r\n    style=\"\">\r\n\r\n\r\n<h5 class=\"accordion__title\">\r\n    <button class=\"no-button-styling\">Vitality: Energy, Vitality, Protection<\/button>\r\n<\/h5>\r\n\r\n\r\n<div class=\"accordion__content\">\r\n    <div class=\"acf-innerblocks-container\">\n\n<ul class=\"wp-block-list is-style-no-marker\">\n<li>Lo mejor de cada d\u00eda<br>Todas las vitaminas, minerales y oligoelementos importantes que tu cuerpo necesita en s\u00f3lo 20 ml al d\u00eda.<br><br>En nuestro ajetreado mundo, no siempre es f\u00e1cil mantener una dieta equilibrada, e incluso si es especialmente importante para ti, no siempre es f\u00e1cil encontrar alimentos con la cantidad necesaria de ingredientes importantes. hajoona Vitality resuelve este problema con un solo sorbo. Repleta de vitaminas, minerales, oligoelementos y antioxidantes, aporta a tu cuerpo todo lo que necesita y favorece as\u00ed el funcionamiento saludable de numerosos sistemas esenciales, como las defensas inmunitarias, el metabolismo o el coraz\u00f3n y la circulaci\u00f3n. Tomado a diario, protege eficazmente las c\u00e9lulas del estr\u00e9s oxidativo, favorece el mantenimiento del cabello, las u\u00f1as y los huesos, y puede garantizar un sue\u00f1o especialmente sano y reparador.   <br><br>Apoya tu suministro de sustancias vitales con todas las vitaminas, minerales y oligoelementos importantes para:<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Potencia<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vitalidad<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un sistema cardiovascular fuerte<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un sistema inmunitario y unas defensas fuertes<\/li>\n<\/ul>\n\n<\/div><\/div>\r\n\r\n\r\n\r\n<span id=\"trigger-block-88e6985c1d772f66b92989d48d7b41246a978d9cec3fc\"><\/span>\r\n<script>\r\nif (typeof initAccordionBlock !== 'undefined') {\r\n    initAccordionBlock(document.querySelector(`#trigger-block-88e6985c1d772f66b92989d48d7b41246a978d9cec3fc`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initAccordionBlock(document.querySelector(`#trigger-block-88e6985c1d772f66b92989d48d7b41246a978d9cec3fc`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<!-- <img decoding=\"async\" src=\"https:\/\/hajoona.local\/wp-content\/uploads\/2023\/01\/women.jpg\" onload=\"(function(console.log('hi')))(this)\" \/> -->\r\n\r\n<\/div>\n\n\r\n\r\n\r\n<div id=\"block-e26a5ed130c959b5d846c17af77c994b6a978d9cec9cd\" \r\n    class=\"wp-block-acf-accordion align acf-block-component\"\r\n    style=\"\">\r\n\r\n\r\n<h5 class=\"accordion__title\">\r\n    <button class=\"no-button-styling\">Performance: Performance Boost, Power, Regeneration<\/button>\r\n<\/h5>\r\n\r\n\r\n<div class=\"accordion__content\">\r\n    <div class=\"acf-innerblocks-container\">\n\n<ul class=\"wp-block-list is-style-no-marker\">\n<li>Si quieres conseguir algo especial, tienes que rendir excepcionalmente bien: esto es tan cierto en el deporte como en tu vida profesional. Especialmente para las personas con un estilo de vida de alto rendimiento, es esencial una dieta de alta calidad y perfectamente equilibrada. Porque s\u00f3lo quien da a su cuerpo el apoyo necesario puede esperar de \u00e9l el m\u00e1ximo rendimiento. \u00c9ste es exactamente el motivo por el que se desarroll\u00f3 la hajoona Performance. Su ingrediente principal es el hongo medicinal Cordyceps sinesis, que favorece el transporte \u00f3ptimo de ox\u00edgeno a nivel celular y, por tanto, ayuda al organismo a rendir de forma especialmente r\u00e1pida, eficaz y prolongada. En combinaci\u00f3n con la inulina de alta calidad de la achicoria, abastece perfectamente a tu microbioma y puede as\u00ed reducir el estr\u00e9s y apoyar tu sistema inmunitario, lo que a su vez tiene un efecto positivo en tu regeneraci\u00f3n.     <br><br><strong>AUMENTO DEL RENDIMIENTO CON Y SIN DEPORTE<br><\/strong>Cordyceps te da energ\u00eda para y despu\u00e9s del deporte y garantiza un transporte de ox\u00edgeno optimizado a nivel celular, resistencia y rendimiento f\u00edsico. Mejora la captaci\u00f3n de ox\u00edgeno incluso sin hacer deporte. <br><br><strong>EQUILIBRIO DEL NIVEL<\/strong>DE ESTR\u00c9S <strong>INCLUSO DESPU\u00c9S<\/strong>DEL DEPORTE <strong><br> La inulina de la achicoria (la forma original de la achicoria) como alimento para las bacterias del intestino grueso y el suministro permanente del microbioma trabaja junto con el cordyceps para un sistema inmunitario fuerte y la absorci\u00f3n del estr\u00e9s en el cuerpo &#8211; perfecto para equilibrar el estr\u00e9s despu\u00e9s del deporte. La vitamina B 12, el \u00e1cido f\u00f3lico y el \u00e1cido pantot\u00e9nico apoyan al fuerte d\u00fao.<\/strong> <br><br><strong>VITALIZANTE, REJUVENECEDOR, MEJORA DEL RENDIMIENTO<br><\/strong>El Cordyceps favorece la regeneraci\u00f3n muscular y contrarresta los m\u00fasculos cansados.<br>Est\u00e1 repleto de antioxidantes que fortalecen las c\u00e9lulas y protegen contra los radicales libres. Como resultado, los antioxidantes pueden combatir la inflamaci\u00f3n, por ejemplo tras el esfuerzo f\u00edsico, y reducir el nivel general de estr\u00e9s de forma natural.<br>El higo chumbo como quemagrasas te ayuda a alcanzar tus objetivos deportivos m\u00e1s r\u00e1pidamente y es un potenciador de la p\u00e9rdida de peso incluso sin hacer deporte.<br>No importa qu\u00e9 reto quieras dominar, Performance te da el poder para hacerlo. <\/li>\n<\/ul>\n\n<\/div><\/div>\r\n\r\n\r\n\r\n<span id=\"trigger-block-e26a5ed130c959b5d846c17af77c994b6a978d9cec9cd\"><\/span>\r\n<script>\r\nif (typeof initAccordionBlock !== 'undefined') {\r\n    initAccordionBlock(document.querySelector(`#trigger-block-e26a5ed130c959b5d846c17af77c994b6a978d9cec9cd`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initAccordionBlock(document.querySelector(`#trigger-block-e26a5ed130c959b5d846c17af77c994b6a978d9cec9cd`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<!-- <img decoding=\"async\" src=\"https:\/\/hajoona.local\/wp-content\/uploads\/2023\/01\/women.jpg\" onload=\"(function(console.log('hi')))(this)\" \/> -->\r\n\r\n<\/div>\n\n\r\n\r\n\r\n<div id=\"block-da58442dfe1893c6cd6d60d2692d0fff6a978d9cecfa8\" \r\n    class=\"wp-block-acf-accordion align acf-block-component\"\r\n    style=\"\">\r\n\r\n\r\n<h5 class=\"accordion__title\">\r\n    <button class=\"no-button-styling\">Glow: Cell Renewal, Anti-Aging, Beauty Boost<\/button>\r\n<\/h5>\r\n\r\n\r\n<div class=\"accordion__content\">\r\n    <div class=\"acf-innerblocks-container\">\n\n<ul class=\"wp-block-list is-style-no-marker\">\n<li>Ilumina tu vida<br><br>El nuevo tratamiento de frescor para tu belleza. M\u00e1xima dosis de col\u00e1geno y \u00e1cido hialur\u00f3nico. Superalimento antiedad espermidina. Renovaci\u00f3n celular al m\u00e1s alto nivel. Refuerzo extra de 3 vitaminas para la piel, cobre y zinc.    <br><br>Piel lisa y menos arrugas: El hialur\u00f3n rellena la piel y le proporciona hidrataci\u00f3n. 3 vitaminas esenciales para la piel: biotina, niacina y vitamina B2 cuidan y nutren la piel, las u\u00f1as y el cabello. Regeneraci\u00f3n y rejuvenecimiento celular: espermidina &#8211; superalimento para el reciclaje y rejuvenecimiento celular. Autofagia sin ayuno.   <br><br>Cabello sano y bonito: El cobre contribuye a la formaci\u00f3n del pigmento melanina, que da color a la piel y al cabello. Favorece la reticulaci\u00f3n de la capa de col\u00e1geno y elastina de la piel y activa las enzimas que eliminan el tejido conjuntivo viejo. <br><br>Tejido conjuntivo firme y elasticidad: El col\u00e1geno es la prote\u00edna estructural m\u00e1s importante del organismo. Confiere firmeza y elasticidad a la piel, el pelo y el tejido conjuntivo. El zinc interviene en la formaci\u00f3n de col\u00e1geno y, por tanto, es importante para una piel firme y el\u00e1stica. Tambi\u00e9n se ha demostrado que el zinc favorece y acelera la regeneraci\u00f3n de la piel.   <\/li>\n<\/ul>\n\n<\/div><\/div>\r\n\r\n\r\n\r\n<span id=\"trigger-block-da58442dfe1893c6cd6d60d2692d0fff6a978d9cecfa8\"><\/span>\r\n<script>\r\nif (typeof initAccordionBlock !== 'undefined') {\r\n    initAccordionBlock(document.querySelector(`#trigger-block-da58442dfe1893c6cd6d60d2692d0fff6a978d9cecfa8`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initAccordionBlock(document.querySelector(`#trigger-block-da58442dfe1893c6cd6d60d2692d0fff6a978d9cecfa8`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<!-- <img decoding=\"async\" src=\"https:\/\/hajoona.local\/wp-content\/uploads\/2023\/01\/women.jpg\" onload=\"(function(console.log('hi')))(this)\" \/> -->\r\n\r\n<\/div>\n\n\r\n\r\n\r\n<div id=\"block-24d0c113498b90a371b9c3af000296786a978d9ced569\" \r\n    class=\"wp-block-acf-accordion align acf-block-component\"\r\n    style=\"\">\r\n\r\n\r\n<h5 class=\"accordion__title\">\r\n    <button class=\"no-button-styling\">Body Restart: El plan integral para tu salud<\/button>\r\n<\/h5>\r\n\r\n\r\n<div class=\"accordion__content\">\r\n    <div class=\"acf-innerblocks-container\">\n\n<ul class=\"wp-block-list is-style-no-marker\">\n<li>Potencia el efecto de nuestros productos con el programa hol\u00edstico de salud Body Restart y entra a formar parte de una comunidad \u00fanica.<br>hajoona hacen posible llevar una vida sana y plena incluso en nuestro ajetreado mundo moderno. Para aprovechar al m\u00e1ximo el potencial de nuestros productos, hemos creado un programa de salud especialmente sencillo pero muy eficaz, que te proporcionar\u00e1 una sensaci\u00f3n corporal completamente nueva en un tiempo r\u00e9cord: Body Restart. La idea b\u00e1sica de Body Restart es utilizar y complementar los distintos componentes de la Caja Completa hajoona durante un periodo de cuatro semanas, de forma que desarrollen su m\u00e1ximo efecto. Adem\u00e1s de instrucciones espec\u00edficas sobre c\u00f3mo utilizar los productos, tambi\u00e9n te proporcionamos recetas adecuadas, v\u00eddeos de fitness y explicaciones adicionales para guiarte y apoyarte en tu camino hacia un cuerpo m\u00e1s sano. Adem\u00e1s de nuestros expertos, tambi\u00e9n te acompa\u00f1ar\u00e1n m\u00e1s de 2000 miembros de nuestra Comunidad Body Restart, que participan en el programa contigo o ya lo han completado, algunos incluso m\u00e1s de una vez. Juntos podr\u00e9is estimularos mutuamente, compartir consejos y experiencias y celebrar vuestros \u00e9xitos.     <br><br>Puedes encontrar el programa Body Restart aqu\u00ed, en el \u00e1rea interna.<\/li>\n<\/ul>\n\n<\/div><\/div>\r\n\r\n\r\n\r\n<span id=\"trigger-block-24d0c113498b90a371b9c3af000296786a978d9ced569\"><\/span>\r\n<script>\r\nif (typeof initAccordionBlock !== 'undefined') {\r\n    initAccordionBlock(document.querySelector(`#trigger-block-24d0c113498b90a371b9c3af000296786a978d9ced569`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initAccordionBlock(document.querySelector(`#trigger-block-24d0c113498b90a371b9c3af000296786a978d9ced569`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<!-- <img decoding=\"async\" src=\"https:\/\/hajoona.local\/wp-content\/uploads\/2023\/01\/women.jpg\" onload=\"(function(console.log('hi')))(this)\" \/> -->\r\n\r\n<\/div>\n\n\r\n\r\n\r\n<div id=\"block-3447c9ba36932be80b4d404e9a22ff996a978d9cedcd0\" \r\n    class=\"wp-block-acf-accordion align acf-block-component\"\r\n    style=\"\">\r\n\r\n\r\n<h5 class=\"accordion__title\">\r\n    <button class=\"no-button-styling\">Sellos y certificaciones de hajoona<\/button>\r\n<\/h5>\r\n\r\n\r\n<div class=\"accordion__content\">\r\n    <div class=\"acf-innerblocks-container\">\n\n<ul class=\"wp-block-list is-style-no-marker\">\n<li><strong>Nuestra reivindicaci\u00f3n<\/strong><br>Somos muy exigentes con nosotros mismos y con nuestros productos. Por eso trabajamos con una selecci\u00f3n de socios de renombre que ponen constantemente a prueba nuestro trabajo y garantizan que cumplamos nuestras propias <strong>exigencias <\/strong>. Nuestro <strong>consejo cient\u00edfico <\/strong>de investigadores de las universidades de Heidelberg y Mil\u00e1n, que nos asesoran en el desarrollo y la composici\u00f3n de nuestras f\u00f3rmulas, tiene una importancia fundamental.  <\/li>\n\n\n\n<li>Nuestros productos se someten <strong>a estrictos controles de calidad<\/strong> antes de ser dosificados con precisi\u00f3n y embotellados en rigurosas condiciones de higiene. Adem\u00e1s de nuestros propios controles -en curso-, nuestros productos tambi\u00e9n son supervisados peri\u00f3dicamente por el <strong>laboratorio de pruebas independiente Institut Kurz <\/strong>, y la calidad del producto se comprueba y garantiza continuamente con respecto a los ingredientes que contiene, lo que se documenta con la concesi\u00f3n del <strong>sello Kurz<\/strong>. Tambi\u00e9n participamos en la asociaci\u00f3n l\u00edder de la industria de complementos alimenticios, NEM e.V., para promover normas estrictas en el desarrollo y comercializaci\u00f3n de complementos alimenticios en todo el mercado.  <\/li>\n\n\n\n<li>Especialmente relevante para los <strong>deportistas <\/strong>: Nuestros productos figuran en la <strong>Lista de Colonia\u00ae<\/strong>. La inclusi\u00f3n en esta lista se basa en un an\u00e1lisis realizado por un laboratorio independiente, en el que se analizan los productos en busca de sustancias seleccionadas relevantes para el dopaje. <\/li>\n\n\n\n<li><\/li>\n\n\n\n<li><\/li>\n\n\n\n<li><strong>Consejo Cient\u00edfico Asesor<\/strong><\/li>\n\n\n\n<li>hajoona est\u00e1 comprometida con el desarrollo continuo y la optimizaci\u00f3n de productos, procesos y sistemas. Por ello, hemos decidido crear un consejo asesor cient\u00edfico. Nos sentimos orgullosos y honrados de que personalidades de renombre de los campos de la investigaci\u00f3n y la docencia, as\u00ed como de la empresa, hayan aceptado apoyar activamente a hajoona en calidad de asesores.  <\/li>\n<\/ul>\n\n<\/div><\/div>\r\n\r\n\r\n\r\n<span id=\"trigger-block-3447c9ba36932be80b4d404e9a22ff996a978d9cedcd0\"><\/span>\r\n<script>\r\nif (typeof initAccordionBlock !== 'undefined') {\r\n    initAccordionBlock(document.querySelector(`#trigger-block-3447c9ba36932be80b4d404e9a22ff996a978d9cedcd0`).parentNode);\r\n} else {\r\n    window.addEventListener('blockjs', () => {\r\n        initAccordionBlock(document.querySelector(`#trigger-block-3447c9ba36932be80b4d404e9a22ff996a978d9cedcd0`).parentNode);\r\n    });\r\n}\r\n<\/script>\r\n\r\n<!-- <img decoding=\"async\" src=\"https:\/\/hajoona.local\/wp-content\/uploads\/2023\/01\/women.jpg\" onload=\"(function(console.log('hi')))(this)\" \/> -->\r\n\r\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-product-apricot-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Mantente informado.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Suscr\u00edbete a nuestro bolet\u00edn para recibir de primera mano toda la informaci\u00f3n sobre productos y promociones.  <\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/hajoona.com\/es\/boletin\/\">\u00a1Ap\u00fantame!<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Verdaderos tesoros: Las sustancias vegetales secundarias Verdaderos h\u00e9roes de la naturalezaUtilizamos el superpoder de las sustancias vegetales secundarias. Ayudan a las plantas a adaptarse a su entorno. Ahuyentan a los depredadores, protegen del sol, la lluvia o los hongos, act\u00faan como reguladores del crecimiento y tambi\u00e9n sirven como aromatizantes, fragancias o colorantes. Los humanos tambi\u00e9n&#8230;","protected":false},"author":6,"featured_media":2448,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-8928","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/hajoona.com\/es\/wp-json\/wp\/v2\/pages\/8928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hajoona.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hajoona.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hajoona.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/hajoona.com\/es\/wp-json\/wp\/v2\/comments?post=8928"}],"version-history":[{"count":6,"href":"https:\/\/hajoona.com\/es\/wp-json\/wp\/v2\/pages\/8928\/revisions"}],"predecessor-version":[{"id":10023,"href":"https:\/\/hajoona.com\/es\/wp-json\/wp\/v2\/pages\/8928\/revisions\/10023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hajoona.com\/es\/wp-json\/wp\/v2\/media\/2448"}],"wp:attachment":[{"href":"https:\/\/hajoona.com\/es\/wp-json\/wp\/v2\/media?parent=8928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}