{"id":9636,"date":"2026-06-18T09:57:52","date_gmt":"2026-06-18T07:57:52","guid":{"rendered":"https:\/\/hajoona.com\/tilbagekaldelse\/"},"modified":"2026-06-18T14:39:14","modified_gmt":"2026-06-18T12:39:14","slug":"tilbagekaldelse-2","status":"publish","type":"page","link":"https:\/\/hajoona.com\/da\/tilbagekaldelse-2\/","title":{"rendered":"Tilbagekaldelse"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Bekr\u00e6ftelsesside for din tilbagekaldelse<\/strong><\/h2>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9622-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"9622\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/da\/wp-json\/wp\/v2\/pages\/9636#wpcf7-f9622-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9622\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9622-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"is-layout-constrained\">\n\t<div>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"salutation\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"salutation\"><option value=\"Hr.\">Hr.<\/option><option value=\"Fru\">Fru<\/option><\/select><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"is-layout-flex wp-block-columns\">\n\t\t<div class=\"is-layout-flow wp-block-column\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"firstname\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Fornavn\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"is-layout-flow wp-block-column\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"lastname\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Efternavn\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"street-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"street\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Gade og husnummer\" value=\"\" type=\"text\" name=\"street-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"is-layout-flex wp-block-columns\">\n\t\t<div class=\"is-layout-flow wp-block-column\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"zip-code\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"zip\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Postnummer\" value=\"\" type=\"text\" name=\"zip-code\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"is-layout-flow wp-block-column\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"city\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"By\" value=\"\" type=\"text\" name=\"city\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"lastname\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Land\" value=\"\" type=\"text\" name=\"country\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mailadresse\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"client-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Kundenummer\" value=\"\" type=\"text\" name=\"client-number\" \/><\/span>\n\t\t<\/p>\n\t\t<p class=\"form-note\">Dit kundenummer best\u00e5r af 6 cifre.\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Telefonnummer\" value=\"\" type=\"tel\" name=\"tel\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><label for=\"reason-for-termination\">Bestillingsnr. \/ Fakturanr.<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"invoice-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"invoice-number\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"invoice-number\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t\t<p><span id=\"wpcf7-6a978d95a29a0-wrapper\" class=\"wpcf7-form-control-wrap cf7apps-honeypot-wrap honeypot-927-wrap\" data-cf7apps-honeypot=\"honeypot-927\" style=\"position:absolute;width:1px;height:1px;padding:0;margin:-1px;overflow:hidden;clip:rect(0,0,0,0);white-space:nowrap;border:0;\"><input type=\"hidden\" name=\"honeypot-927-random-hash\" value=\"20260902\"><input type=\"hidden\" name=\"honeypot-927-time-token\" value=\"MTc4ODMxNzA3Nw==.3c38c6dd655d5b760f18e87413f1c7d2d342c5ad6ce8298323b7c41035a079a9\"><label\n\t\t    for=\"wpcf7-6a978d95a29a0-field\"\n\t\t    class=\"hp-message\"\n        >Bitte lasse dieses Feld leer.<\/label><input\n\t    id=\"wpcf7-6a978d95a29a0-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"abhahqpritle\"\n\t    value=\"\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n\t    data-cf7apps-tabindex=\"1000\"\n    \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div>\n\t<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner wp-element-button\" type=\"submit\" value=\"Fortryd nu\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"Bekr\u00e6ftelsesside for din tilbagekaldelse","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-9636","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/hajoona.com\/da\/wp-json\/wp\/v2\/pages\/9636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hajoona.com\/da\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hajoona.com\/da\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hajoona.com\/da\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hajoona.com\/da\/wp-json\/wp\/v2\/comments?post=9636"}],"version-history":[{"count":2,"href":"https:\/\/hajoona.com\/da\/wp-json\/wp\/v2\/pages\/9636\/revisions"}],"predecessor-version":[{"id":9665,"href":"https:\/\/hajoona.com\/da\/wp-json\/wp\/v2\/pages\/9636\/revisions\/9665"}],"wp:attachment":[{"href":"https:\/\/hajoona.com\/da\/wp-json\/wp\/v2\/media?parent=9636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}